{"id":7146,"date":"2018-07-25T10:00:40","date_gmt":"2018-07-25T08:00:40","guid":{"rendered":"https:\/\/www.diedruckerei.de\/magazin\/?p=7146"},"modified":"2025-04-28T16:14:39","modified_gmt":"2025-04-28T14:14:39","slug":"plaque-mousse-legere-decoupe-contour-panneaux","status":"publish","type":"post","link":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/","title":{"rendered":"Tutoriel InDesign\u00a0: plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour"},"content":{"rendered":"<p>Tout le monde conna\u00eet ces enseignes situ\u00e9es devant l&rsquo;entr\u00e9e de chaque entreprise. Petite, moyenne, grande et, dans la plupart des cas, de forme rectangulaire\u00a0! Si vous voulez sortir de cette monotonie, voici la r\u00e9ponse pour votre enseigne\u00a0: la \u00ab\u00a0d\u00e9coupe du contour\u00a0\u00bb. En effet, un panneau publicitaire avec une d\u00e9coupe du contour permet de r\u00e9aliser une forme compl\u00e8tement individuelle. Dans cet atelier, vous apprendrez comment cr\u00e9er correctement les donn\u00e9es d&rsquo;impression pour obtenir une plaque en mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour.<\/p>\n<p><!--more--><\/p>\n<h3>Table des mati\u00e8res de cet article\u00a0:<\/h3>\n<ul>\n<li><a href=\"#decoupe-contour\">Qu\u2019est-ce qu\u2019une d\u00e9coupe du contour\u00a0?<\/a><\/li>\n<li><a href=\"#comment-decoupe-contour\">Comment fonctionne la d\u00e9coupe du contour\u00a0?<\/a><\/li>\n<li><a href=\"#software\">Utiliser le bon logiciel<\/a><\/li>\n<li><a href=\"#specifications\">Sp\u00e9cifications pour la cr\u00e9ation<\/a><\/li>\n<li><a href=\"#vase-tulipes\">L\u2019exemple pratique\u00a0: le vase de tulipes<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 id=\"decoupe-contour\">Qu\u2019est-ce qu\u2019une d\u00e9coupe du contour\u00a0?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10897 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-1024x682.jpg\" alt=\"Une machine de d\u00e9coupe de pr\u00e9cision d\u00e9coupe le contour d&#039;un imprim\u00e9 floral \u00e9clatant. L&#039;image illustre le processus m\u00e9canique, avec des feuilles vertes et des fleurs roses m\u00e9ticuleusement d\u00e9coup\u00e9es le long de leurs contours.\" width=\"696\" height=\"464\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-1024x682.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-300x200.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-768x512.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-696x464.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-1068x712.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour-630x420.jpg 630w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/1-decoupe-du-contour.jpg 1088w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>Gr\u00e2ce \u00e0 une machine sp\u00e9ciale, la plaque rectangulaire est d\u00e9coup\u00e9e pour cr\u00e9er une forme individuelle. Il peut s&rsquo;agir, par exemple, d&rsquo;un logo rond ou d&rsquo;un lettrage complet, dont les formes sont redessin\u00e9es gr\u00e2ce \u00e0 une d\u00e9coupe du contour. La d\u00e9coupe du contour peut \u00eatre utilis\u00e9e lorsque la forme rectangle classique n&rsquo;est pas adapt\u00e9e. Le choix des mat\u00e9riaux comprend des panneaux l\u00e9gers ainsi que des panneaux en mousse rigide, en aluminium DIBOND ainsi que des plaques alv\u00e9olaires. Tous les mat\u00e9riaux sont \u00e9galement utilisables \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"comment-decoupe-contour\">Comment fonctionne la d\u00e9coupe du contour\u00a0?<\/h2>\n<p>Afin que la machine de d\u00e9coupe sache quelle forme elle doit cr\u00e9er, certaines informations doivent \u00eatre int\u00e9gr\u00e9es sous forme de chemin dans le projet d&rsquo;impression. Cependant, ce chemin n&rsquo;est pas imprim\u00e9, mais sp\u00e9cifie seulement l&rsquo;information de position pour la t\u00eate de coupe.<\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"software\">Utiliser le bon logiciel<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10898 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-1024x576.jpg\" alt=\"Les logos d&#039;Adobe Illustrator et d&#039;Adobe InDesign sont affich\u00e9s c\u00f4te \u00e0 c\u00f4te sur un fond de planche de bois. Le logo Illustrator, repr\u00e9sentant la d\u00e9coupe du contour, est encadr\u00e9 d&#039;un cadre orange avec Ai au centre, tandis que le logo InDesign arbore un cadre magenta avec Id au centre.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/2-decoupe-du-contour_logiciel.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>Adobe Illustrator et Adobe InDesign sont les mieux adapt\u00e9s \u00e0 la cr\u00e9ation d&rsquo;un tel chemin. Gr\u00e2ce \u00e0 eux, des trajectoires vectorielles peuvent \u00eatre cr\u00e9\u00e9es et trait\u00e9es de mani\u00e8re \u00e0 ce que la t\u00eate de coupe puisse suivre de mani\u00e8re optimale les informations relatives \u00e0 la trajectoire.<\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"specifications\">Sp\u00e9cifications pour la cr\u00e9ation<\/h2>\n<p>Comme tout projet d&rsquo;impression, la d\u00e9coupe des contours comprend \u00e9galement des conditions pr\u00e9alables qui doivent \u00eatre remplies pour obtenir le r\u00e9sultat d\u00e9sir\u00e9. L&rsquo;exigence de base est de cr\u00e9er un chemin ferm\u00e9\u00a0: le point de d\u00e9part doit donc correspondre au point final. De plus, le chemin ne doit pas contenir d&rsquo;ar\u00eates pointues et le rayon du coin ne doit pas \u00eatre inf\u00e9rieur \u00e0 4\u00a0mm. En principe, il peut y avoir des diff\u00e9rences de coupe de 1 \u00e0 2\u00a0mm. Il devrait donc y avoir suffisamment d&rsquo;espace entre le sujet r\u00e9el et la trajectoire de coupe. Nous recommandons une distance de s\u00e9curit\u00e9 d&rsquo;au moins 3\u00a0mm. La r\u00e8gle est la suivante\u00a0: plut\u00f4t trop que pas assez.<\/p>\n<p>Le chemin en lui-m\u00eame est color\u00e9 \u00e0 100 % magenta avec la couleur aplat sp\u00e9cialement cr\u00e9\u00e9e \u00ab CutContour \u00bb, l&rsquo;\u00e9paisseur de contour appropri\u00e9e est de 0,5 ou 1 pt. Cependant, l&rsquo;\u00e9paisseur du contour est d&rsquo;une importance purement destin\u00e9e \u00e0 l\u2019appr\u00e9ciation de la forme et sans importance pour la d\u00e9coupe ult\u00e9rieure, puisque le contour n&rsquo;est pas imprim\u00e9 et que la machine de d\u00e9coupe s&rsquo;aligne sur les informations de base du chemin, et non sur l&rsquo;\u00e9paisseur du contour.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"custom-background custom-background-donts\">\n<h3>Remarque importante\u00a0:<\/h3>\n<p>assurez-vous de s\u00e9lectionner le titre \u00ab CutContour \u00bb comme nom pour la nouvelle couleur aplat. C&rsquo;est la seule fa\u00e7on pour la machine de reconna\u00eetre qu&rsquo;il s&rsquo;agit d&rsquo;une trajectoire de d\u00e9coupe.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h2 id=\"vase-tulipes\">L\u2019exemple pratique\u00a0: le vase de tulipes<\/h2>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10899 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-1024x576.jpg\" alt=\"Un vase blanc contient des tulipes roses aux longues feuilles vertes, sur fond de mur de briques blanches flou. L&#039;image, r\u00e9alis\u00e9e avec pr\u00e9cision par d\u00e9coupe du contour, s&#039;affiche dans l&#039;interface d&#039;un logiciel de conception, avec des outils et des options autour de l&#039;espace de travail.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/3-decoupe-du-contour_l-exemple.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Dans cet exemple, ce motif floral doit \u00eatre transform\u00e9 en une forme individuelle \u00e0 l&rsquo;aide d&rsquo;une d\u00e9coupe du contour. L&rsquo;image dispose d\u2019une r\u00e9solution de 300\u00a0dpi, la taille \u00e9tant adapt\u00e9e \u00e0 un projet de taille moyenne. Ce sont des conditions parfaites car la r\u00e9solution des panneaux publicitaires doit \u00eatre d&rsquo;au moins 120\u00a0dpi. Nous aimerions imprimer un panneau publicitaire carr\u00e9, 50\u00a0x\u00a050\u00a0cm, sur KAPA Plast (5\u00a0mm).<\/p>\n<p>Comme toujours, nous utilisons le mod\u00e8le InDesign pour le fichier de donn\u00e9es d&rsquo;impression. Celui-ci se trouve dans la boutique en ligne sur la page produit. Il contient d\u00e9j\u00e0 tous les pr\u00e9r\u00e9glages pour l&rsquo;exportation PDF correcte. Seule la trajectoire pour la d\u00e9coupe du contour doit \u00eatre cr\u00e9\u00e9e manuellement.<\/p>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10900 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-1024x576.jpg\" alt=\"Une capture d&#039;\u00e9cran d&#039;Adobe InDesign r\u00e9v\u00e8le un document vierge avec des r\u00e8gles, des marges et des rep\u00e8res visibles, parfaits pour une mise en page pr\u00e9cise. L&#039;interface propose des barres d&#039;outils et des options de menu, id\u00e9ales pour cr\u00e9er des designs complexes, comme des projets de \u00ab\u00a0d\u00e9coupe du contour\u00a0\u00bb.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/4-decoupe-du-contour_fichier.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Nous ouvrons donc le mod\u00e8le t\u00e9l\u00e9charg\u00e9 avec InDesign, dessinons un cadre et pla\u00e7ons l&rsquo;image avec le raccourci <span class=\"shortcut\">Ctrl<\/span> + <span class=\"shortcut\">D<\/span> dans notre mod\u00e8le. Il est recommand\u00e9 de placer l&rsquo;image sur son propre calque et de la verrouiller dans la <span class=\"guideline\">Fen\u00eatre de calques<\/span> afin qu&rsquo;elle ne soit pas d\u00e9plac\u00e9e par inadvertance. Nous cr\u00e9ons ensuite un nouveau calque s\u00e9par\u00e9 pour la d\u00e9coupe du contour.<\/p>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10901 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-1024x576.jpg\" alt=\"Un \u00e9cran d&#039;ordinateur affiche une bo\u00eete de dialogue intitul\u00e9e \u00ab\u00a0Options de nuance\u00a0\u00bb, avec des curseurs de r\u00e9glage des couleurs pour le cyan, le magenta, le jaune et le noir. En arri\u00e8re-plan, contre un mur clair, un vase flou contient des tulipes roses, dont les contours sont l\u00e9g\u00e8rement d\u00e9coup\u00e9s.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/5-decoupe-du-conotur_options-nuance.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>L&rsquo;\u00e9tape suivante consiste \u00e0 appliquer la couleur \u00ab CutContour \u00bb. Pour ce faire, nous ouvrons le <span class=\"guideline\">Nuancier<\/span> et cliquons sur <span class=\"guideline\">Nouveau champ de couleur<\/span>. Nous appelons ce nouveau champ de couleur \u00ab CutContour \u00bb. Cette d\u00e9signation est absolument n\u00e9cessaire, car ce n&rsquo;est que de cette fa\u00e7on que la machine de d\u00e9coupe peut reconna\u00eetre le chemin color\u00e9 avec cette couleur comme chemin de coupe. Nous r\u00e9glons \u00e9galement le type de couleur pour la <span class=\"guideline\">Couleur aplat<\/span> et d\u00e9finissons la composition des couleurs comme \u00e9tant 100\u00a0% magenta. Confirmer les r\u00e9glages avec <span class=\"guideline\">Ok<\/span>.<\/p>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10902 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-1024x576.jpg\" alt=\"Capture d&#039;\u00e9cran d&#039;un espace de travail Adobe InDesign montrant un document avec un vase de tulipes roses sur fond clair. Le panneau Nuancier est ouvert, affichant diff\u00e9rents \u00e9chantillons de couleurs, mettant en \u00e9vidence l&#039;option \u00ab\u00a0D\u00e9coupe du contour\u00a0\u00bb. Les options du menu sont en fran\u00e7ais.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/6-decoupe-du-contour_CutContour.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Maintenant, nous cr\u00e9ons le chemin autour du motif d\u00e9sir\u00e9. Dans le panneau Outils, nous s\u00e9lectionnons l\u2019<span class=\"guideline\">Outils crayon <\/span> et recherchons un point de d\u00e9part en laissant une large distance par rapport au motif r\u00e9el. Pour d\u00e9finir un nouveau point de chemin, on clique sur l&#8217;emplacement d\u00e9sir\u00e9. Nous maintenons le bouton de la souris enfonc\u00e9 et d\u00e9pla\u00e7ons la souris plus loin, testons \u00e0 droite et \u00e0 gauche. De cette fa\u00e7on, nous d\u00e9finissons la courbure du segment de courbe cr\u00e9\u00e9 et une trajectoire droite devient une courbe. Lors du r\u00e9glage des points et de l&rsquo;alignement de la courbe r\u00e9sultante, un peu de tact est n\u00e9cessaire. Notre alli\u00e9 pour cela\u00a0: <span class=\"shortcut\">Ctrl<\/span> + <span class=\"shortcut\">Z<\/span>. En appuyant sur la touche <span class=\"shortcut\">Ctrl<\/span>, nous pouvons \u00e9galement cliquer sur les diff\u00e9rents points de chemin et corriger la position et l&rsquo;angle si n\u00e9cessaire.<\/p>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10903 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-1024x576.jpg\" alt=\"L&#039;interface d&#039;un logiciel de conception num\u00e9rique affiche une photo de tulipes roses dans un vase blanc sur un mur de briques blanches. Des barres d&#039;outils et des guides, enrichis par la fonction de d\u00e9coupe du contour, entourent la photo, indiquant qu&#039;elle est en cours de modification ou de formatage.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/7-decoupe-du-contour_outils-crayon.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Veillez \u00e0 maintenir une distance \u00e9gale par rapport au sujet. Une fois que tous les points de chemin ont \u00e9t\u00e9 d\u00e9finis, nous compl\u00e9tons le chemin en cliquant sur le point de d\u00e9part. Le tour est jou\u00e9\u00a0!<\/p>\n<p><a href=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-10904 size-large\" src=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-1024x576.jpg\" alt=\"Capture d&#039;\u00e9cran de l&#039;interface d&#039;un logiciel de conception affichant une image de tulipes roses dans un vase blanc. Un contour rouge clair, probablement destin\u00e9 \u00e0 la d\u00e9coupe du contour ou \u00e0 la s\u00e9lection, met en valeur les fleurs. La page est partiellement visible, avec des barres d&#039;outils en haut et sur les c\u00f4t\u00e9s.\" width=\"696\" height=\"392\" srcset=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-1024x576.jpg 1024w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-300x169.jpg 300w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-768x432.jpg 768w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-696x392.jpg 696w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-1068x601.jpg 1068w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance-747x420.jpg 747w, https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/8-decoupe-du-contour_distance.jpg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Enfin, nous nous assurons que le chemin soit vraiment color\u00e9 avec la couleur \u00ab CutContour \u00bb.<\/p>\n<p>Le projet d&rsquo;impression peut maintenant \u00eatre sauvegard\u00e9 sous forme de fichier PDF via <span class=\"guideline\">Fichier &gt; Exporter<\/span>. Gr\u00e2ce \u00e0 notre mod\u00e8le, nous n&rsquo;avons pas besoin de faire d&rsquo;autres r\u00e9glages dans la <span class=\"guideline\">Fen\u00eatre Exportation<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Notre vase de tulipes est une d\u00e9coration id\u00e9ale pour le bureau, la caf\u00e9t\u00e9ria ou la salle \u00e0 manger. Conform\u00e9ment au cahier des charges de la d\u00e9coupe des contours, il n&rsquo;y a pas de limite \u00e0 la cr\u00e9ativit\u00e9\u00a0: un beau motif comme notre vase, un lettrage courbe, une mascotte, le logo de l&rsquo;entreprise. Il n&rsquo;est pas n\u00e9cessaire qu&rsquo;il y ait toujours quatre angles droits\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<div class=\"custom-background custom-background-dos\">\n<p>&nbsp;<\/p>\n<p>Vous trouverez toutes les informations sur la <a href=\"https:\/\/www.onlineprinters.fr\/c\/donnees-d-impression\/coupure-du-contour\" target=\"_blank\" rel=\"noopener noreferrer\">d\u00e9coupe du contour<\/a> et bien d&rsquo;autres sujets li\u00e9s \u00e0 la cr\u00e9ation, la sauvegarde et la transmission des donn\u00e9es d&rsquo;impression dans l\u2019espace <a href=\"https:\/\/www.onlineprinters.fr\/c\/besoin-aide\" target=\"_blank\" rel=\"noopener noreferrer\">Aide \/ F.A.Q.<\/a> d\u2019Onlineprinters.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"custom-background-grey\">\n<h3>Cr\u00e9dits\u00a0:<\/h3>\n<p><span style=\"font-size: 10pt;\">ce tutoriel est con\u00e7u et comment\u00e9 par le concepteur multim\u00e9dia Christoph Ullrich.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tout le monde conna\u00eet ces enseignes situ\u00e9es devant l&rsquo;entr\u00e9e de chaque entreprise. Petite, moyenne, grande et, dans la plupart des cas, de forme rectangulaire\u00a0! Si vous voulez sortir de cette monotonie, voici la r\u00e9ponse pour votre enseigne\u00a0: la \u00ab\u00a0d\u00e9coupe du contour\u00a0\u00bb. En effet, un panneau publicitaire avec une d\u00e9coupe du contour permet de r\u00e9aliser une [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":10925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tutoriel InDesign\u00a0: plaque en mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour \u2013 panneaux publicitaires<\/title>\n<meta name=\"description\" content=\"Les panneaux publicitaires n&#039;ont pas besoin d&#039;\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d&#039;une d\u00e9coupe du contour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutoriel InDesign\u00a0: plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour\" \/>\n<meta property=\"og:description\" content=\"Les panneaux publicitaires n&#039;ont pas besoin d&#039;\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d&#039;une d\u00e9coupe du contour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/\" \/>\n<meta property=\"og:site_name\" content=\"onlineprinters.fr MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-25T08:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T14:14:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anja\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tutoriel InDesign\u00a0: plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anja\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/\",\"url\":\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/\",\"name\":\"Tutoriel InDesign\u00a0: plaque en mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour \u2013 panneaux publicitaires\",\"isPartOf\":{\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg\",\"datePublished\":\"2018-07-25T08:00:40+00:00\",\"dateModified\":\"2025-04-28T14:14:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/45300fa80141df03ebbfd029c34ddff6\"},\"description\":\"Les panneaux publicitaires n'ont pas besoin d'\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d'une d\u00e9coupe du contour.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage\",\"url\":\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg\",\"contentUrl\":\"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg\",\"width\":1280,\"height\":720,\"caption\":\"plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/#website\",\"url\":\"https:\/\/www.onlineprinters.fr\/blog\/\",\"name\":\"onlineprinters.fr MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.onlineprinters.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/45300fa80141df03ebbfd029c34ddff6\",\"name\":\"Anja\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/33e09db5879706c8bfa6e82308d6157b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/33e09db5879706c8bfa6e82308d6157b?s=96&d=mm&r=g\",\"caption\":\"Anja\"},\"url\":\"https:\/\/www.onlineprinters.fr\/blog\/author\/anja\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutoriel InDesign\u00a0: plaque en mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour \u2013 panneaux publicitaires","description":"Les panneaux publicitaires n'ont pas besoin d'\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d'une d\u00e9coupe du contour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Tutoriel InDesign\u00a0: plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour","og_description":"Les panneaux publicitaires n'ont pas besoin d'\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d'une d\u00e9coupe du contour.","og_url":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/","og_site_name":"onlineprinters.fr MAGAZINE","article_published_time":"2018-07-25T08:00:40+00:00","article_modified_time":"2025-04-28T14:14:39+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg","type":"image\/jpeg"}],"author":"Anja","twitter_card":"summary_large_image","twitter_title":"Tutoriel InDesign\u00a0: plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour","twitter_misc":{"\u00c9crit par":"Anja","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/","url":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/","name":"Tutoriel InDesign\u00a0: plaque en mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour \u2013 panneaux publicitaires","isPartOf":{"@id":"https:\/\/www.onlineprinters.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage"},"image":{"@id":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg","datePublished":"2018-07-25T08:00:40+00:00","dateModified":"2025-04-28T14:14:39+00:00","author":{"@id":"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/45300fa80141df03ebbfd029c34ddff6"},"description":"Les panneaux publicitaires n'ont pas besoin d'\u00eatre de forme rectangulaire. Des formes individuelles peuvent \u00e9galement \u00eatre r\u00e9alis\u00e9es au moyen d'une d\u00e9coupe du contour.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.onlineprinters.fr\/blog\/plaque-mousse-legere-decoupe-contour-panneaux\/#primaryimage","url":"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg","contentUrl":"https:\/\/www.onlineprinters.fr\/blog\/wp-content\/uploads\/2018\/07\/plaque-mousse-legere.jpg","width":1280,"height":720,"caption":"plaque mousse l\u00e9g\u00e8re avec d\u00e9coupe du contour"},{"@type":"WebSite","@id":"https:\/\/www.onlineprinters.fr\/blog\/#website","url":"https:\/\/www.onlineprinters.fr\/blog\/","name":"onlineprinters.fr MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onlineprinters.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/45300fa80141df03ebbfd029c34ddff6","name":"Anja","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.onlineprinters.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/33e09db5879706c8bfa6e82308d6157b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33e09db5879706c8bfa6e82308d6157b?s=96&d=mm&r=g","caption":"Anja"},"url":"https:\/\/www.onlineprinters.fr\/blog\/author\/anja\/"}]}},"_links":{"self":[{"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/posts\/7146"}],"collection":[{"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/comments?post=7146"}],"version-history":[{"count":7,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/posts\/7146\/revisions"}],"predecessor-version":[{"id":53202,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/posts\/7146\/revisions\/53202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/media\/10925"}],"wp:attachment":[{"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/media?parent=7146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/categories?post=7146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onlineprinters.fr\/blog\/wp-json\/wp\/v2\/tags?post=7146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}